{"id":7205,"date":"2021-11-30T12:39:12","date_gmt":"2021-11-30T12:39:12","guid":{"rendered":"https:\/\/sfihealthsolutions.com\/private-label\/cardiocare\/"},"modified":"2021-12-02T00:42:48","modified_gmt":"2021-12-02T00:42:48","slug":"cardiocare","status":"publish","type":"cpt_private_label","link":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/","title":{"rendered":"CardioCare"},"content":{"rendered":"\n<section id=\"private-label-single-block_61a060f44f067\" class=\"block-private-label-single\">\n    <div class=\"container\">\n        <div class=\"row align-items-top\">\n            <div class=\"col-lg-6 product-img-w100\">\n                                                                     <img loading=\"lazy\" decoding=\"async\" width=\"1870\" height=\"1950\" src=\"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare.jpg 1870w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-288x300.jpg 288w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-982x1024.jpg 982w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-768x801.jpg 768w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-1473x1536.jpg 1473w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-32x32.jpg 32w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-52x54.jpg 52w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-37x39.jpg 37w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-100x104.jpg 100w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-105x110.jpg 105w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-646x674.jpg 646w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-251x262.jpg 251w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-462x482.jpg 462w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-611x637.jpg 611w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-486x507.jpg 486w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-364x380.jpg 364w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-520x542.jpg 520w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-328x342.jpg 328w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-355x370.jpg 355w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-451x470.jpg 451w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare-547x570.jpg 547w\" sizes=\"(max-width: 1870px) 100vw, 1870px\" \/>                            <\/div>\n            <div class=\"col-lg-5\">\n                <span class=\"tag-title\">Cardiovascular<\/span>\n                <h1>CardioCare<\/h1>\n                <p>*actualmente solo puede venderse fuera de Europa.<\/p>\n<p><strong>CardioCare es un complemento que proporciona una fuente concentrada y de alta calidad de \u00e1cidos grasos y omega-3 procedentes del aceite de pescado (una fuente de EPA y DHA), junto con la coenzima Q10 y la vitamina E para favorecer una actividad card\u00edaca saludable. Es un complemento sin colorantes, aromatizantes ni conservantes artificiales, sin az\u00facares a\u00f1adidos, aspartamo ni sacarina.<\/strong><\/p>\n<p>Por favor, aseg\u00farate de que los dise\u00f1os e ilustraciones de los envases locales cumplen con los requisitos reglamentarios locales.<\/p>\n<p>Disponible en 30 o 60.<\/p>\n                                                    <a class=\"btn btn-primary\" href=\"https:\/\/sfihealthsolutions.com\/es\/contacto\/\" target=\"\">Concertar una consulta<\/a>\n                                                    <div class=\"accordion animate-children mt-4\">\n                                                        <div class=\"card-collapse\">\n                                    <div class=\"card-collapse-header\" id=\"heading0\">\n                                            <h4 class=\"mb-0\">\n                                                <button class=\"btn collapsed w-100\" type=\"button\" data-toggle=\"collapse\"\n                                                data-target=\"#collapse0\" aria-expanded=\"false\"\n                                                aria-controls=\"collapse0\">\n                                                \u00bfPara qui\u00e9n est\u00e1 indicado?                                            <\/button>\n                                        <\/h4>\n                                    <\/div>\n                                    <div id=\"collapse0\" class=\"collapse\" aria-labelledby=\"heading0\">\n                                        <div class=\"card-body\">\n                                            <p>18-65 a\u00f1os<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                        <div class=\"card-collapse\">\n                                    <div class=\"card-collapse-header\" id=\"heading1\">\n                                            <h4 class=\"mb-0\">\n                                                <button class=\"btn collapsed w-100\" type=\"button\" data-toggle=\"collapse\"\n                                                data-target=\"#collapse1\" aria-expanded=\"false\"\n                                                aria-controls=\"collapse1\">\n                                                \u00bfC\u00f3mo se toma?                                            <\/button>\n                                        <\/h4>\n                                    <\/div>\n                                    <div id=\"collapse1\" class=\"collapse\" aria-labelledby=\"heading1\">\n                                        <div class=\"card-body\">\n                                            <p>1 c\u00e1psula al d\u00eda durante al menos 4-8 semanas.<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                        <div class=\"card-collapse\">\n                                    <div class=\"card-collapse-header\" id=\"heading2\">\n                                            <h4 class=\"mb-0\">\n                                                <button class=\"btn collapsed w-100\" type=\"button\" data-toggle=\"collapse\"\n                                                data-target=\"#collapse2\" aria-expanded=\"false\"\n                                                aria-controls=\"collapse2\">\n                                                Ingredientes                                            <\/button>\n                                        <\/h4>\n                                    <\/div>\n                                    <div id=\"collapse2\" class=\"collapse\" aria-labelledby=\"heading2\">\n                                        <div class=\"card-body\">\n                                            <p>&#8211; EPA (\u00c1cido eicosapentaenoico): 375 mg<br \/>\n&#8211; DHA (\u00c1cido docosahexaenoico): 45 mg<br \/>\n&#8211; Coenzima Q10: 10 mg<\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n        \n            <h2><\/h2>\n            <div class=\"row align-items-center\">\n\n                            <div class=\"col-lg-4 d-flex mb-4 align-items-center private-label-benefits\">\n                    <div class=\"col-3 col-sm-2 col-lg-3 \">\n                                                                                                  <img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"104\" src=\"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/enviromental-icon.svg\" class=\"attachment-full size-full\" alt=\"\" \/>                                            <\/div>\n                    <div class=\"col-sm-10 col-lg-8\">\n                        <p>Procedente de fuentes sostenibles<\/p>\n                    <\/div>\n                <\/div>\n                            <div class=\"col-lg-4 d-flex mb-4 align-items-center private-label-benefits\">\n                    <div class=\"col-3 col-sm-2 col-lg-3 \">\n                                                                                                  <img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"104\" src=\"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/sugar.svg\" class=\"attachment-full size-full\" alt=\"\" \/>                                            <\/div>\n                    <div class=\"col-sm-10 col-lg-8\">\n                        <p>Sin az\u00facares a\u00f1adidos<\/p>\n                    <\/div>\n                <\/div>\n                            <div class=\"col-lg-4 d-flex mb-4 align-items-center private-label-benefits\">\n                    <div class=\"col-3 col-sm-2 col-lg-3 \">\n                                                                                                  <img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"104\" src=\"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/ticks.svg\" class=\"attachment-full size-full\" alt=\"\" \/>                                            <\/div>\n                    <div class=\"col-sm-10 col-lg-8\">\n                        <p>Sin colorantes, aromatizantes ni conservantes artificiales<\/p>\n                    <\/div>\n                <\/div>\n                        <\/div>\n                                        <br>\n            <h2><\/h2><br>\n                            <div class=\"row row-cols-md-3 row-cols-sm-2 row-cols-1 gutters-44\">\n                                         \n                    <div class=\"col d-flex\">\n                        <div class=\"card card-reset\">\n                            <a class=\"card-title\" href=\"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/memorease\/\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1870\" height=\"1950\" src=\"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease.png 1870w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-288x300.png 288w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-982x1024.png 982w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-768x801.png 768w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-1473x1536.png 1473w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-32x32.png 32w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-52x54.png 52w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-37x39.png 37w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-100x104.png 100w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-67x70.png 67w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-646x674.png 646w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-251x262.png 251w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-462x482.png 462w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-611x637.png 611w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-486x507.png 486w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-364x380.png 364w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-520x542.png 520w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-328x342.png 328w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-355x370.png 355w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-451x470.png 451w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/memorease-547x570.png 547w\" sizes=\"(max-width: 1870px) 100vw, 1870px\" \/>                            <\/a>\n                            <div class=\"card-body d-flex flex-column\">\n                                <h5 class=\"h5\">MemorEase<\/h5>\n                                <div class=\"d-flex\">\n                                                                            <span class=\"tag-title\">Cognici\u00f3n<\/span>\n                                                                    <\/div>\n                                <div class=\"desc-container\">\n                                    MemorEase favorece la concentraci\u00f3n mental y la memoria aliviando la ansiedad.                                <\/div>\n                                <a class=\"link mt-auto align-self-baseline\" href=\"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/memorease\/\">Lee mas<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                         \n                    <div class=\"col d-flex\">\n                        <div class=\"card card-reset\">\n                            <a class=\"card-title\" href=\"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/phytodefense\/\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1496\" height=\"1560\" src=\"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense.png 1496w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-288x300.png 288w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-982x1024.png 982w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-768x801.png 768w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-1473x1536.png 1473w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-32x32.png 32w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-52x54.png 52w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-37x39.png 37w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-100x104.png 100w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-67x70.png 67w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-646x674.png 646w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-251x262.png 251w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-462x482.png 462w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-611x637.png 611w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-486x507.png 486w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-364x380.png 364w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-520x542.png 520w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-328x342.png 328w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-355x370.png 355w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-451x470.png 451w, https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/Phytodefense-547x570.png 547w\" sizes=\"(max-width: 1496px) 100vw, 1496px\" \/>                            <\/a>\n                            <div class=\"card-body d-flex flex-column\">\n                                <h5 class=\"h5\">PhytoDefense<\/h5>\n                                <div class=\"d-flex\">\n                                                                            <span class=\"tag-title\">Immunity<\/span>\n                                                                            <span class=\"tag-title\">Inmunidad<\/span>\n                                                                    <\/div>\n                                <div class=\"desc-container\">\n                                    PhytoDefense refuerza y equilibra el sistema inmunitario para hacer frente a las infecciones mejorando las molestias inflamatorias.\r\n                                <\/div>\n                                <a class=\"link mt-auto align-self-baseline\" href=\"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/phytodefense\/\">Lee mas<\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n                        <\/div>\n        <\/section>","protected":false},"excerpt":{"rendered":"<p>CardioCare es un complemento que proporciona una fuente concentrada y de alta calidad de \u00e1cidos grasos y omega-3 procedentes del aceite de pescado (una fuente de EPA y DHA), junto con la coenzima Q10 y la vitamina E para favorecer una actividad card\u00edaca saludable.<\/p>\n","protected":false},"featured_media":8204,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[],"tags":[106],"class_list":["post-7205","cpt_private_label","type-cpt_private_label","status-publish","has-post-thumbnail","hentry","tag-cardiovascular-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CardioCare SFI Health Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CardioCare SFI Health Solutions\" \/>\n<meta property=\"og:description\" content=\"CardioCare es un complemento que proporciona una fuente concentrada y de alta calidad de \u00e1cidos grasos y omega-3 procedentes del aceite de pescado (una fuente de EPA y DHA), junto con la coenzima Q10 y la vitamina E para favorecer una actividad card\u00edaca saludable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/\" \/>\n<meta property=\"og:site_name\" content=\"SFI Health Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T00:42:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1870\" \/>\n\t<meta property=\"og:image:height\" content=\"1950\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/marca-propia\\\/cardiocare\\\/\",\"url\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/marca-propia\\\/cardiocare\\\/\",\"name\":\"CardioCare SFI Health Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/marca-propia\\\/cardiocare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/marca-propia\\\/cardiocare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sfihealthsolutions.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cardiocare.jpg\",\"datePublished\":\"2021-11-30T12:39:12+00:00\",\"dateModified\":\"2021-12-02T00:42:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/marca-propia\\\/cardiocare\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/marca-propia\\\/cardiocare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/marca-propia\\\/cardiocare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sfihealthsolutions.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cardiocare.jpg\",\"contentUrl\":\"https:\\\/\\\/sfihealthsolutions.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cardiocare.jpg\",\"width\":1870,\"height\":1950},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/marca-propia\\\/cardiocare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Private Label\",\"item\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/marca-propia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CardioCare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/\",\"name\":\"SFI Health Solutions\",\"description\":\"Your Global Specialist Nutraceutical and Pharmaceutical CDMO\",\"publisher\":{\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/#organization\",\"name\":\"SFI Health Solutions\",\"url\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sfihealthsolutions.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/image-placeholder.jpg\",\"contentUrl\":\"https:\\\/\\\/sfihealthsolutions.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/image-placeholder.jpg\",\"width\":426,\"height\":426,\"caption\":\"SFI Health Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/sfihealthsolutions.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CardioCare SFI Health Solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/","og_locale":"es_ES","og_type":"article","og_title":"CardioCare SFI Health Solutions","og_description":"CardioCare es un complemento que proporciona una fuente concentrada y de alta calidad de \u00e1cidos grasos y omega-3 procedentes del aceite de pescado (una fuente de EPA y DHA), junto con la coenzima Q10 y la vitamina E para favorecer una actividad card\u00edaca saludable.","og_url":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/","og_site_name":"SFI Health Solutions","article_modified_time":"2021-12-02T00:42:48+00:00","og_image":[{"width":1870,"height":1950,"url":"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/","url":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/","name":"CardioCare SFI Health Solutions","isPartOf":{"@id":"https:\/\/sfihealthsolutions.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/#primaryimage"},"image":{"@id":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/#primaryimage"},"thumbnailUrl":"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare.jpg","datePublished":"2021-11-30T12:39:12+00:00","dateModified":"2021-12-02T00:42:48+00:00","breadcrumb":{"@id":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/#primaryimage","url":"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare.jpg","contentUrl":"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/11\/cardiocare.jpg","width":1870,"height":1950},{"@type":"BreadcrumbList","@id":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/cardiocare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sfihealthsolutions.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Private Label","item":"https:\/\/sfihealthsolutions.com\/es\/marca-propia\/"},{"@type":"ListItem","position":3,"name":"CardioCare"}]},{"@type":"WebSite","@id":"https:\/\/sfihealthsolutions.com\/es\/#website","url":"https:\/\/sfihealthsolutions.com\/es\/","name":"SFI Health Solutions","description":"Your Global Specialist Nutraceutical and Pharmaceutical CDMO","publisher":{"@id":"https:\/\/sfihealthsolutions.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sfihealthsolutions.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sfihealthsolutions.com\/es\/#organization","name":"SFI Health Solutions","url":"https:\/\/sfihealthsolutions.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sfihealthsolutions.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/06\/image-placeholder.jpg","contentUrl":"https:\/\/sfihealthsolutions.com\/wp-content\/uploads\/2021\/06\/image-placeholder.jpg","width":426,"height":426,"caption":"SFI Health Solutions"},"image":{"@id":"https:\/\/sfihealthsolutions.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sfihealthsolutions.com\/es\/wp-json\/wp\/v2\/cpt_private_label\/7205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sfihealthsolutions.com\/es\/wp-json\/wp\/v2\/cpt_private_label"}],"about":[{"href":"https:\/\/sfihealthsolutions.com\/es\/wp-json\/wp\/v2\/types\/cpt_private_label"}],"replies":[{"embeddable":true,"href":"https:\/\/sfihealthsolutions.com\/es\/wp-json\/wp\/v2\/comments?post=7205"}],"version-history":[{"count":0,"href":"https:\/\/sfihealthsolutions.com\/es\/wp-json\/wp\/v2\/cpt_private_label\/7205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sfihealthsolutions.com\/es\/wp-json\/wp\/v2\/media\/8204"}],"wp:attachment":[{"href":"https:\/\/sfihealthsolutions.com\/es\/wp-json\/wp\/v2\/media?parent=7205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sfihealthsolutions.com\/es\/wp-json\/wp\/v2\/categories?post=7205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sfihealthsolutions.com\/es\/wp-json\/wp\/v2\/tags?post=7205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}